{"id":235274,"date":"2022-03-31T15:39:47","date_gmt":"2022-03-31T14:39:47","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=235274"},"modified":"2022-03-31T15:39:47","modified_gmt":"2022-03-31T14:39:47","slug":"prisao-preventiva-para-detido-por-tentativa-de-homicidio-em-coimbra","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/prisao-preventiva-para-detido-por-tentativa-de-homicidio-em-coimbra\/","title":{"rendered":"Pris\u00e3o preventiva para detido por tentativa de homic\u00eddio em Coimbra"},"content":{"rendered":"<p data-uw-styling-context=\"true\"><a href=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/03\/Policia-Judiciaria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-233138\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/03\/Policia-Judiciaria.jpg\" alt=\"\" width=\"1200\" height=\"628\" \/><\/a><\/p>\n<p data-uw-styling-context=\"true\">Um homem de 34 anos ficou em pris\u00e3o preventiva ap\u00f3s ser detido por suspeita da pr\u00e1tica de um crime de homic\u00eddio qualificado, na forma tentada, em Coimbra, anunciou hoje a Pol\u00edcia Judici\u00e1ria (PJ).<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O crime aconteceu na madrugada do dia 19 de fevereiro \u00e0 porta de um espa\u00e7o de divers\u00e3o noturna, na Pra\u00e7a da Rep\u00fablica, na cidade de Coimbra.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O ofendido, de 21 anos, estudante universit\u00e1rio, estava \u201cna companhia de um amigo nesse bar e houve ali uma confus\u00e3o relacionado com outro grupo de pessoas\u201d.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O homem de 34 anos, que trabalhava nesse bar, interveio na situa\u00e7\u00e3o e \u201cdepois dessa interven\u00e7\u00e3o h\u00e1 ali tens\u00f5es, empurr\u00f5es e algumas agress\u00f5es f\u00edsicas\u201d, disse fonte da PJ \u00e0 ag\u00eancia Lusa.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">\u201cOs indiv\u00edduos, o ofendido e o amigo, afastaram-se do local e esse indiv\u00edduo, funcion\u00e1rio do bar, vai atr\u00e1s deles e surpreende-os, esfaqueando um deles\u201d, na zona de Celas, acrescentou.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">Um deles consegue afastar-se, \u201cpercebendo as inten\u00e7\u00f5es dele [do detido]\u201d.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">No entanto, a \u201cv\u00edtima n\u00e3o consegue e \u00e9 surpreendida com um esfaqueamento\u201d.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">Dada a gravidade dos ferimentos, o amigo da v\u00edtima conduziu-o ao hospital universit\u00e1rio, onde ficou internado.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">Segundo a PJ, a situa\u00e7\u00e3o foi estabilizada e a v\u00edtima teve alta hospitalar.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">A PJ deu ainda nota de que o suspeito possui um \u201cextenso cadastro criminal\u201d, designadamente por crimes de homic\u00eddio na forma tentada e crime de tr\u00e1fico de estupefacientes.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O homem foi detido na ter\u00e7a-feira e presente a primeiro interrogat\u00f3rio judicial, na quarta-feira, tendo-lhe sido aplicada a medida de coa\u00e7\u00e3o de pris\u00e3o preventiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 34 anos ficou em pris\u00e3o preventiva ap\u00f3s ser detido por suspeita da pr\u00e1tica de um crime de homic\u00eddio qualificado, na forma tentada, em Coimbra, anunciou hoje a Pol\u00edcia Judici\u00e1ria (PJ).<\/p>\n","protected":false},"author":1,"featured_media":233138,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,31],"tags":[40,1788],"class_list":["post-235274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coimbra-2","category-geral","tag-coimbra","tag-prisao"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/235274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=235274"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/235274\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=235274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=235274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=235274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}