{"id":235526,"date":"2022-04-05T10:29:20","date_gmt":"2022-04-05T09:29:20","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=235526"},"modified":"2022-04-05T10:29:20","modified_gmt":"2022-04-05T09:29:20","slug":"em-coimbra-escolas-apresentam-nova-exposicao-reviver-saramago","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/em-coimbra-escolas-apresentam-nova-exposicao-reviver-saramago\/","title":{"rendered":"Em Coimbra escolas apresentam nova exposi\u00e7\u00e3o  \u201c(Re)viver Saramago\u201d"},"content":{"rendered":"<p><a href=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/04\/08-Saramago.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-235527\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/04\/08-Saramago.jpg\" alt=\"\" width=\"1200\" height=\"628\" \/><\/a><\/p>\n<p>Numa iniciativa integrada na comemora\u00e7\u00e3o do Centen\u00e1rio de Jos\u00e9 Saramago (1922-2022), a C\u00e2mara de Coimbra promove, a partir de amanh\u00e3 \u2013 na Casa Municipal da Cultura \u2013 a exposi\u00e7\u00e3o \u201c(Re)viver Saramago \u2013 1922-2022\u201d.<\/p>\n<p>A exposi\u00e7\u00e3o abre ao p\u00fablico, \u00e0s 14H30, na Galeria Pinho Dinis. A mostra vai exibir os trabalhos produzidos por alunos que frequentam as escolas da Rede de Bibliotecas de Coimbra baseados na obra do escritor Jos\u00e9 Saramago.<\/p>\n<p><strong>(Ler reportagem completa na edi\u00e7\u00e3o impressa do DI\u00c1RIO AS BEIRAS em 05\/04\/2022)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Numa iniciativa integrada na comemora\u00e7\u00e3o do Centen\u00e1rio de Jos\u00e9 Saramago (1922-2022), a C\u00e2mara de Coimbra promove, a partir de amanh\u00e3 \u2013 na Casa Municipal da Cultura \u2013 a exposi\u00e7\u00e3o \u201c(Re)viver Saramago \u2013 1922-2022\u201d<\/p>\n","protected":false},"author":1,"featured_media":235527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,31],"tags":[40,7799],"class_list":["post-235526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coimbra-2","category-geral","tag-coimbra","tag-saramago"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/235526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=235526"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/235526\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=235526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=235526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=235526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}