{"id":238280,"date":"2022-05-09T15:56:36","date_gmt":"2022-05-09T14:56:36","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=238280"},"modified":"2022-05-09T15:56:36","modified_gmt":"2022-05-09T14:56:36","slug":"autarcas-e-dezenas-de-praticantes-inauguram-parque-de-skate-em-coimbra","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/autarcas-e-dezenas-de-praticantes-inauguram-parque-de-skate-em-coimbra\/","title":{"rendered":"Autarcas e dezenas de praticantes inauguram parque de skate em Coimbra"},"content":{"rendered":"<div id=\"txt\" data-uw-styling-context=\"true\">\n<div id=\"attachment_238281\" style=\"width: 1210px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.asbeiras.pt\/2022\/05\/autarcas-e-dezenas-de-praticantes-inauguram-parque-de-skate-em-coimbra\/inauguracao-do-parque-municipal-de-skate-ma-5\/\" rel=\"attachment wp-att-238281\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-238281\" class=\"size-full wp-image-238281\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/05\/Inauguracao-do-Parque-Municipal-de-Skate-MA-5.jpg\" alt=\"\" width=\"1200\" height=\"628\" \/><\/a><p id=\"caption-attachment-238281\" class=\"wp-caption-text\">Foto DB|e|Miguel Almeida<\/p><\/div>\n<p data-uw-styling-context=\"true\">Algumas dezenas de skaters inauguraram hoje o Parque Municipal de Skate, em Coimbra, situado sob o viaduto da Ponte Rainha Santa Isabel, uma obra or\u00e7ada em cerca de 452 mil euros.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">\u201cEra um espa\u00e7o que faltava a Coimbra\u201d. A cidade disp\u00f5e agora de \u201cmais um espa\u00e7o de pr\u00e1tica desportiva, de lazer, de divers\u00e3o, de conv\u00edvio, que \u00e9 extremamente importante e que fazia falta\u201d, disse, na inaugura\u00e7\u00e3o do parque, o presidente da C\u00e2mara Municipal de Coimbra, Jos\u00e9 Manuel Silva.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">Este novo parque situado na margem direita do rio Mondego, tem uma \u00e1rea de 1.500 metros quadrados e custou cerca de 452 mil euros.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O recinto divide-se em quatro zonas, uma das quais destinada a quem est\u00e1 a ter o primeiro contacto com a modalidade, na disciplina de \u2018street\u2019 e \u2018bowl\u2019.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">A zona dois \u00e9 de inicia\u00e7\u00e3o ao \u2018street\u2019 skate, com uma quadra para o n\u00edvel iniciante.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">J\u00e1 a zona tr\u00eas contempla \u2018street\u2019 skate avan\u00e7ado e \u00e9 composta por duas quadras distintas, que representam dois n\u00edveis de progress\u00e3o, sendo a quadra mais elevada desenvolvida para enquadramento competitivo nacional, isto \u00e9, para servir de palco, por exemplo, ao Campeonato Nacional de Skate, na vertente \u2018street\u2019.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">A zona quatro \u00e9 destinada \u00e0 disciplina de \u2018bowl\u2019, apresentando diversos n\u00edveis de dificuldade integrada.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">\u201cTemos aqui uma obra excelente e que cumpriu as regras do \u2018skateboarding\u2019 internacional, portanto podem fazer-se aqui grandes provas internacionais o problema \u00e9 a limita\u00e7\u00e3o de espa\u00e7o. Isso ser\u00e1 uma condicionante\u201d, explicou o autarca.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">\u201c\u00c9 uma obra que Coimbra se pode orgulhar, que vem corresponder aquilo que eram os anseios da juventude amantes de skate, que j\u00e1 h\u00e1 muitos anos, vinham solicitando, exigindo e reclamando um espa\u00e7o destes, que em boa hora foi constru\u00eddo e que agora nos vai permitir dar um impulso a esta modalidade, que \u00e9 uma modalidade ol\u00edmpica\u201d, sublinhou.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">O vereador do Desporto, Carlos Lopes, deu nota de que o munic\u00edpio est\u00e1 em \u201cconversa\u00e7\u00f5es tamb\u00e9m com a Federa\u00e7\u00e3o Portuguesa de Patinagem\u201d, para preparar um evento que dignifique a pr\u00e1tica desportiva desta modalidade.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">A inaugura\u00e7\u00e3o foi feita em conjunto com o ex-presidente da C\u00e2mara Municipal de Coimbra, Manuel Machado, j\u00e1 que foi uma obra que teve in\u00edcio no executivo anterior.<\/p>\n<p class=\"text-paragraph\" data-uw-styling-context=\"true\">Questionado pelos jornalistas sobre o policiamento na zona do parque, Jos\u00e9 Manuel Silva sublinhou que \u201cn\u00e3o h\u00e1 raz\u00e3o para aumentar o policiamento s\u00f3 por estar aqui uma pista de skate\u201d, adiantando que \u201co circuito que agora inclui esta zona da pista de skate passar\u00e1 tamb\u00e9m a ser regularmente percorrido pelas for\u00e7as de autoridade, no seu circuito de vigil\u00e2ncia da cidade\u201d.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Algumas dezenas de skaters inauguraram hoje o Parque Municipal de Skate, em Coimbra, situado sob o viaduto da Ponte Rainha Santa Isabel, uma obra or\u00e7ada em cerca de 452 mil euros.<\/p>\n","protected":false},"author":1,"featured_media":238281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,31],"tags":[40,8251],"class_list":["post-238280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coimbra-2","category-geral","tag-coimbra","tag-skate"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/238280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=238280"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/238280\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=238280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=238280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=238280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}