{"id":246558,"date":"2022-09-26T11:59:42","date_gmt":"2022-09-26T10:59:42","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=246558"},"modified":"2022-09-26T11:59:42","modified_gmt":"2022-09-26T10:59:42","slug":"opiniao-a-frente-de-rio-do-cabedelo-deve-ser-requalificada","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/opiniao-a-frente-de-rio-do-cabedelo-deve-ser-requalificada\/","title":{"rendered":"Opini\u00e3o: A frente de rio do Cabedelo deve ser requalificada?"},"content":{"rendered":"<p><a href=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2021\/12\/Mafalda-Azenha-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-228585 size-full\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2021\/12\/Mafalda-Azenha-1.jpg\" alt=\"\" width=\"2500\" height=\"1308\" \/><\/a><\/p>\n<p>SIM<br \/>\nE nem tudo est\u00e1 por fazer porque a obra de requalifica\u00e7\u00e3o do Cabedelo j\u00e1 intervencionou uma parte. Ao longo do rio, a zona tem um piso novo e um parque infantil absolutamente enquadrado na paisagem natural e inovador, que faz as del\u00edcias das crian\u00e7as que o descobrem. E do lado do cais, o barco para fazer a travessia h\u00e1-de chegar.<br \/>\nConv\u00e9m que o espa\u00e7o esteja bem equipado e cuidado e que tenha condi\u00e7\u00f5es para todos os queiram ali atracar. A obra do Cabedelo pretendeu ser uma obra estruturante, que criasse a base para ponderar pormenores que continuem a engrandecer aquela zona da cidade. Por isso, n\u00e3o \u00e9 s\u00f3 a zona ribeirinha que deve ter aten\u00e7\u00e3o.<br \/>\n\u00c9 urgente que os particulares que ganharam a concess\u00e3o dos espa\u00e7os na Pra\u00e7a comecem as obras dos seus equipamentos. Caso contr\u00e1rio, daqui a uns tempos, teremos l\u00e1 outra vez uma s\u00e9rie de constru\u00e7\u00f5es prec\u00e1rias a formar um conjunto com um aspeto pouco enquadr\u00e1vel naquilo que hoje \u00e9 aquela frente de mar.<br \/>\nSe n\u00e3o for para instalar escolas de surf ou equipamentos relacionados, \u00e9 preciso saber o que se quer fazer dos edif\u00edcios dos antigos balne\u00e1rios. Pelos menos duas das maiores marcas de surf a n\u00edvel mundial queriam poder investir no edif\u00edcio do restaurante.<br \/>\nO que \u00e9 que j\u00e1 foi feito para que isso possa acontecer? Assim o permitam os tantos \u201cdonos do Cabedelo\u201d, esta parte da cidade \u00e9 um diamante em bruto que merece constante lapida\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opini\u00e3o de Mafalda Azenha<\/p>\n","protected":false},"author":1,"featured_media":228585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31,5],"tags":[6597,100],"class_list":["post-246558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-opiniao","tag-mafalda-azenha","tag-opiniao"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/246558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=246558"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/246558\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=246558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=246558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=246558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}