{"id":246762,"date":"2022-09-28T11:29:52","date_gmt":"2022-09-28T10:29:52","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=246762"},"modified":"2022-09-28T11:29:52","modified_gmt":"2022-09-28T10:29:52","slug":"opiniao-a-frente-de-rio-do-cabedelo-deve-ser-requalificada-3","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/opiniao-a-frente-de-rio-do-cabedelo-deve-ser-requalificada-3\/","title":{"rendered":"Opini\u00e3o: A frente de rio do Cabedelo deve ser requalificada?"},"content":{"rendered":"<p><a href=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/01\/silvina-queiroz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-229671 size-full\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/01\/silvina-queiroz.jpg\" alt=\"\" width=\"2500\" height=\"1308\" \/><\/a><\/p>\n<p>N\u00c3O<br \/>\nOu sim. Dependeria e muito do que qualquer altera\u00e7\u00e3o quisesse ditar. Adivinhar n\u00e3o sei! Contudo, lembro muito bem quais eram as propostas do anterior executivo camar\u00e1rio! Mais umas obras megal\u00f3manas, para benef\u00edcio de bolsos bem recheados, retirando uma vez mais o rio a quem ele pertence. As gentes do Cabedelo, pois. Como na passada semana, de novo me apetece dizer: anule-se o que foi ali feito e que tem dado os \u201cresultados\u201d conhecidos! Aquela extens\u00e3o de asfalto, al\u00e9m de nada dever \u00e0 beleza, \u00e9 um perigo constante. Com o mar galgando tudo por ali acima, mostrando \u00e0 saciedade que n\u00e3o est\u00e1 para brincadeiras! Ainda por cima de gosto duvidoso. A quest\u00e3o do Parque de Campismo, que tantas \u201ccomich\u00f5es\u201d provocava em algumas almas inquietas, \u00e9 paradigm\u00e1tica do estado de esp\u00edrito de algumas mentes com responsabilidades pol\u00edticas. (As responsabilidades que det\u00eam \u00e9 que s\u00e3o o mal!) Sempre dispon\u00edveis para engendrar projectos, planos, \u201csolu\u00e7\u00f5es\u201d que afastem o povo an\u00f3nimo da frui\u00e7\u00e3o do que \u00e9 por natureza seu. Regressando \u00e0 requalifica\u00e7\u00e3o: o que significaria? Mais uns mastodontes como os que foram \u201cplantados\u201d na margem direita?! Tapando o rio, colocando-lhe uma tampa atrevida, feiosa e desenquadrada da envolvente. Deixem o Cabedelo em paz, porque para pior j\u00e1 basta assim! O que fizeram \u00e0 duna prim\u00e1ria \u00e9 absolutamente inaceit\u00e1vel. Por onde anda a APA e pensando em qu\u00ea?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opini\u00e3o de Silvina Queiroz<\/p>\n","protected":false},"author":1,"featured_media":229671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31,5],"tags":[100,6632],"class_list":["post-246762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-opiniao","tag-opiniao","tag-silvina-queiroz"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/246762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=246762"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/246762\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=246762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=246762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=246762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}