{"id":249573,"date":"2022-11-07T17:14:55","date_gmt":"2022-11-07T16:14:55","guid":{"rendered":"https:\/\/www.asbeiras.pt\/?p=249573"},"modified":"2022-11-07T17:14:55","modified_gmt":"2022-11-07T16:14:55","slug":"mumificacao-natural-cresce-em-cemiterios-nacionais-investigadora-u-coimbra","status":"publish","type":"post","link":"https:\/\/critecnow.com\/diariobeiras\/mumificacao-natural-cresce-em-cemiterios-nacionais-investigadora-u-coimbra\/","title":{"rendered":"Mumifica\u00e7\u00e3o natural cresce em cemit\u00e9rios nacionais \u2013 investigadora U. Coimbra"},"content":{"rendered":"<div id=\"attachment_249574\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/11\/Angela-Silva-Bessa-UC.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-249574\" class=\"wp-image-249574 size-full\" src=\"https:\/\/www.asbeiras.pt\/wp-content\/uploads\/2022\/11\/Angela-Silva-Bessa-UC.jpg\" alt=\"\" width=\"1200\" height=\"628\" \/><\/a><p id=\"caption-attachment-249574\" class=\"wp-caption-text\">\u00c2ngela Silva Bessa, investigadora<\/p><\/div>\n<p class=\"text-paragraph\">Os cemit\u00e9rios portugueses registam cada vez mais casos de mumifica\u00e7\u00e3o que acontece de forma natural, provocando constrangimentos em termos de espa\u00e7o, alertou hoje a investigadora em Antropologia Forense da Universidade de Coimbra, \u00c2ngela Silva Bessa.<\/p>\n<p class=\"text-paragraph\">Em declara\u00e7\u00f5es \u00e0 ag\u00eancia Lusa, a investigadora explicou que a mumifica\u00e7\u00e3o natural vem ocorrendo, nos \u00faltimos anos, em cemit\u00e9rios de todo o pa\u00eds, o que obriga a que as sepulturas tempor\u00e1rias permane\u00e7am ocupadas para al\u00e9m dos tr\u00eas anos previstos na lei, at\u00e9 \u00e0 exuma\u00e7\u00e3o do cad\u00e1ver.<\/p>\n<p class=\"text-paragraph\">\u201cA Lei devia ser revista, pois este \u00e9 um problema cada vez maior em Portugal. Se o corpo estiver mumificado, dificilmente vai decompor-se, mesmo que fique inumado por mais dois, quatro ou seis anos\u201d, alegou.<\/p>\n<p class=\"text-paragraph\">De acordo com \u00c2ngela Silva Bessa, a investiga\u00e7\u00e3o que vem realizando nos \u00faltimos tr\u00eas anos, em cemit\u00e9rios do Porto, Braga, Figueira da Foz, M\u00e9rtola e Faro, permitiu registar \u201ccasos em que era a quarta vez que tentavam exumar o cad\u00e1ver\u201d.<\/p>\n<p class=\"text-paragraph\">\u201cA lei diz que no fim de tr\u00eas anos o cad\u00e1ver estar\u00e1 pronto para ser exumado e, no caso das sepulturas tempor\u00e1rias, estas poderem serem reutilizadas. No entanto, quando a decomposi\u00e7\u00e3o cadav\u00e9rica n\u00e3o se verifica, a inuma\u00e7\u00e3o ter\u00e1 de continuar, por per\u00edodos sucessivos de dois anos, em que a cada dois anos se desenterra o corpo e chamam-se os familiares para verificar o seu estado\u201d, descreveu.<\/p>\n<p class=\"text-paragraph\">Para a sua investiga\u00e7\u00e3o, a doutoranda procurou cemit\u00e9rios de todos os pontos do pa\u00eds, de forma a tentar perceber se as diferen\u00e7as de solos estariam a influenciar a decomposi\u00e7\u00e3o cadav\u00e9rica.<\/p>\n<p class=\"text-paragraph\">\u201cOs solos s\u00e3o muito diferentes de norte a sul de Portugal, mas os resultados s\u00e3o muito semelhantes em termos de decomposi\u00e7\u00e3o. Em termos de mat\u00e9ria org\u00e2nica tamb\u00e9m, s\u00e3o muito parecidos entre si\u201d, indicou.<\/p>\n<p class=\"text-paragraph\">Segundo \u00c2ngela Silva Bessa, de 28 anos, ainda n\u00e3o se sabe muito bem o que influencia a decomposi\u00e7\u00e3o humana, embora se acredite que esta ocorra mediante um conjunto de vari\u00e1veis que atuam entre si.<\/p>\n<p class=\"text-paragraph\">\u201cDentro de cada cemit\u00e9rio, mesmo em sepulturas uma ao lado da outra, temos cad\u00e1veres em estados muito diferentes de decomposi\u00e7\u00e3o. O solo \u00e9 igual, logo pensamos que s\u00e3o tamb\u00e9m fatores intr\u00ednsecos ao indiv\u00edduo, que poder\u00e3o estar a causar esta preserva\u00e7\u00e3o cadav\u00e9rica\u201d, admitiu.<\/p>\n<p class=\"text-paragraph\">A bolsa que lhe foi atribu\u00edda, pela Funda\u00e7\u00e3o para a Ci\u00eancia e a Tecnologia (FCT), para a realiza\u00e7\u00e3o do doutoramento em Antropologia Forense na Universidade de Coimbra, termina em outubro de 2023, tendo pela frente mais um ano de investiga\u00e7\u00e3o.<\/p>\n<p class=\"text-paragraph\">\u201cTemos de perceber como \u00e9 que podemos ajudar na acelera\u00e7\u00e3o da decomposi\u00e7\u00e3o cadav\u00e9rica, para depois dos tr\u00eas ou quatro anos termos o corpo para exuma\u00e7\u00e3o\u201d, acrescentou.<\/p>\n<p class=\"text-paragraph\">No seu entender, mesmo que a lei viesse a ser alterada, no sentido de haver um alargamento do prazo de tr\u00eas para cinco anos para a exuma\u00e7\u00e3o do cad\u00e1ver, \u201co problema ir\u00e1 manter-se\u201d.<\/p>\n<p class=\"text-paragraph\">\u201cContinuar\u00edamos com o problema da falta de espa\u00e7o em cemit\u00e9rios, sobretudo nos centros urbanos, onde n\u00e3o \u00e9 poss\u00edvel alargar os cemit\u00e9rios ou construir novos\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os cemit\u00e9rios portugueses registam cada vez mais casos de mumifica\u00e7\u00e3o que acontece de forma natural, provocando constrangimentos em termos de espa\u00e7o, alertou hoje a investigadora em Antropologia Forense da Universidade de Coimbra, \u00c2ngela Silva Bessa.<\/p>\n","protected":false},"author":1,"featured_media":86593,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,31],"tags":[10697,10698,10699,10700],"class_list":["post-249573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coimbra-2","category-geral","tag-angela-silva-bessa","tag-cemiterios-nacionais","tag-investigadora-uc","tag-mumificacao-natural"],"acf":[],"_links":{"self":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/249573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/comments?post=249573"}],"version-history":[{"count":0,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/posts\/249573\/revisions"}],"wp:attachment":[{"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/media?parent=249573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/categories?post=249573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/critecnow.com\/diariobeiras\/wp-json\/wp\/v2\/tags?post=249573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}